{"id":2242,"date":"2025-05-23T10:54:42","date_gmt":"2025-05-23T07:54:42","guid":{"rendered":"http:\/\/18.198.197.203\/ebb-medical-vokietija\/"},"modified":"2026-03-12T08:52:12","modified_gmt":"2026-03-12T06:52:12","slug":"ebb-medical-vokietija","status":"publish","type":"page","link":"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/","title":{"rendered":"Ebb Medical in Deutschland"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2242","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ebb Medical in Deutschland - EBB Medical Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ebb Medical in Deutschland - EBB Medical Group\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/\" \/>\n<meta property=\"og:site_name\" content=\"EBB Medical Group\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T06:52:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/\",\"url\":\"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/\",\"name\":\"Ebb Medical in Deutschland - EBB Medical Group\",\"isPartOf\":{\"@id\":\"https:\/\/www.ebbmedical.com\/#website\"},\"datePublished\":\"2025-05-23T07:54:42+00:00\",\"dateModified\":\"2026-03-12T06:52:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ebbmedical.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ebb Medical in Deutschland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ebbmedical.com\/#website\",\"url\":\"https:\/\/www.ebbmedical.com\/\",\"name\":\"EBB Medical Group\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ebbmedical.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ebb Medical in Deutschland - EBB Medical Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/","og_locale":"de_DE","og_type":"article","og_title":"Ebb Medical in Deutschland - EBB Medical Group","og_url":"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/","og_site_name":"EBB Medical Group","article_modified_time":"2026-03-12T06:52:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/","url":"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/","name":"Ebb Medical in Deutschland - EBB Medical Group","isPartOf":{"@id":"https:\/\/www.ebbmedical.com\/#website"},"datePublished":"2025-05-23T07:54:42+00:00","dateModified":"2026-03-12T06:52:12+00:00","breadcrumb":{"@id":"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ebbmedical.com\/de\/ebb-medical-vokietija\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ebbmedical.com\/de\/"},{"@type":"ListItem","position":2,"name":"Ebb Medical in Deutschland"}]},{"@type":"WebSite","@id":"https:\/\/www.ebbmedical.com\/#website","url":"https:\/\/www.ebbmedical.com\/","name":"EBB Medical Group","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ebbmedical.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ebbmedical.com\/de\/wp-json\/wp\/v2\/pages\/2242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ebbmedical.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ebbmedical.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ebbmedical.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ebbmedical.com\/de\/wp-json\/wp\/v2\/comments?post=2242"}],"version-history":[{"count":18,"href":"https:\/\/www.ebbmedical.com\/de\/wp-json\/wp\/v2\/pages\/2242\/revisions"}],"predecessor-version":[{"id":2415,"href":"https:\/\/www.ebbmedical.com\/de\/wp-json\/wp\/v2\/pages\/2242\/revisions\/2415"}],"wp:attachment":[{"href":"https:\/\/www.ebbmedical.com\/de\/wp-json\/wp\/v2\/media?parent=2242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}